{"id":3879,"date":"2021-05-14T09:32:54","date_gmt":"2021-05-14T07:32:54","guid":{"rendered":"https:\/\/wptesting.radiopark.de\/?p=3879"},"modified":"2021-05-14T09:32:55","modified_gmt":"2021-05-14T07:32:55","slug":"radiopark-austria-trend-hotels","status":"publish","type":"post","link":"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/","title":{"rendered":"Musikalischer Neustart: Radiopark und Austria Trend Hotels&#8230;"},"content":{"rendered":"\n<p><strong>&#8230;gehen mit gest\u00e4rkter Zusammenarbeit aus dem Lockdown.<\/strong><\/p>\n\n\n\n<p><strong>Hamburg, 14. Mai 2021: Noch sind die Zimmer leer und die Bars\ngeschlossen \u2013 seit Monaten k\u00f6nnen Hotels keine G\u00e4ste empfangen. Radiopark und\nAustria Trend Hotels nutzen diese ungew\u00f6hnlichen Zeiten f\u00fcr einen musikalischen\nNeustart. Seit \u00fcber 15 Jahren bespielen die Hamburger Musikspezialisten die\nH\u00e4user der renommierten \u00f6sterreichischen Hotelgruppe. Jetzt legen die\nKooperationspartner ihre Zusammenarbeit neu auf.<\/strong><\/p>\n\n\n\n<p>Sobald die\nHotellerie ab 19. Mai 2021 wieder \u00f6ffnet, starten Radiopark und die Austria\nTrend Hotels ihre erweiterte Zusammenarbeit. Schon seit 2005 vertrauen neun der\nH\u00e4user auf die Expertise der Sounddesigner und Musikredakteure von Radiopark.\nNun festigen die Partner ihre Kooperation und erg\u00e4nzen das Portfolio um neun\nweitere Hotels, die im Laufe des Jahres 2021 mit Musikkonzepten der\nSound-Experten ausgestattet werden.<\/p>\n\n\n\n<p>Mit Hotels in \u00d6sterreich und Slowenien bietet Austria Trend Erlebnisse f\u00fcr unterschiedliche Anspr\u00fcche. Ob Business Travel, Reisende auf Citytrips oder Familien \u2013 die \u00fcber 20 H\u00e4user unterscheiden sich in Zielgruppe und Angebot. Mit Radiopark haben die Hoteliers einen verl\u00e4sslichen Partner an der Seite, der das ganzheitliche Markenkonzept und die individuellen Eigenschaften der Standorte in Einklang bringt.<\/p>\n\n\n\n<p>Der gemeinsame Relaunch nach dem Lockdown soll die Musikkonzepte der ausgew\u00e4hlten H\u00e4user vereinheitlichen. Die Sound-Experten greifen den Charakter der Hotels auf und verwandeln ihn in einzigartige Klangprofile, die perfekt an das Hotelerlebnis angepasst sind.  <\/p>\n\n\n\n<p>Bereits 2020\nerstellte Radiopark ein einheitliches Musikkonzept in enger Zusammenarbeit mit\nBrand- und Hotelverantwortlichen. Mit der gewohnt hohen musikalischen Qualit\u00e4t\nund der routinierten Planung von Radiopark ist die Hotelgruppe musikalisch\nideal auf den Neustart nach der Pandemie vorbereitet.<\/p>\n\n\n\n<p>Arndt-Helge\nGrap, Gesch\u00e4ftsf\u00fchrer von Radiopark,\nfreut sich \u00fcber die internationale Kooperation: \u201eWir haben fr\u00fch erkannt, dass\ndie richtige musikalische Umgebung essentiell f\u00fcr das Hotelerlebnis ist. Mit\nden Austria Trend Hotels haben wir einen Partner gefunden, der unsere Expertise\nseit Jahren zu sch\u00e4tzen wei\u00df. Daher ist es umso sch\u00f6ner, dass wir die\nPartnerschaft in Zukunft st\u00e4rken, um gemeinsam aus der Pandemie zu kommen.\u201c<\/p>\n\n\n\n<p>\u201eGutes Sounddesign macht sich im Hotel schnell bemerkbar: Wenn sich\nunsere G\u00e4ste nach der Musik in Lobby oder Bar erkundigen, haben wir akustisch\neine besondere Atmosph\u00e4re geschaffen. Die Austria Trend Hotels setzen seit \u00fcber\n15 Jahren auf die Zusammenarbeit mit Radiopark. Wir freuen uns, die\nerfolgreiche Kooperation nun um neun weitere Hotels zu erweitern\u201c, erkl\u00e4rt\nMichael Kr\u00f6ger, Gesch\u00e4ftsf\u00fchrer der Verkehrsb\u00fcro Hotellerie. <\/p>\n\n\n\n<p>Dass Austria Trend Hotels mit Radiopark auf den richtigen Dienstleister setzt, verr\u00e4t ein Blick in das Kundenportfolio der Hamburger Musikliebhaber. Neben Retail und Kreuzfahrt bespielt das Team um Arndt-Helge Grap etliche f\u00fchrende Hotels im In- und Ausland.<\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG218252_Austria_Trend_Hotel_Rathauspark_AuSZenansicht-1-1024x682.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG218252_Austria_Trend_Hotel_Rathauspark_AuSZenansicht-1-1024x682.jpeg\" alt=\"\" data-id=\"3884\" data-link=\"https:\/\/wptesting.radiopark.de\/?attachment_id=3884\" class=\"wp-image-3884\" srcset=\"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG218252_Austria_Trend_Hotel_Rathauspark_AuSZenansicht-1-1024x682.jpeg 1024w, https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG218252_Austria_Trend_Hotel_Rathauspark_AuSZenansicht-1-300x200.jpeg 300w, https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG218252_Austria_Trend_Hotel_Rathauspark_AuSZenansicht-1-768x512.jpeg 768w, https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG218252_Austria_Trend_Hotel_Rathauspark_AuSZenansicht-1-1080x720.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption>RHW Au\u00dfenansicht<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/Radisson_blu_hotel_altstadt_deutscheStube_c_austria_trend_hotels-1024x683.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/Radisson_blu_hotel_altstadt_deutscheStube_c_austria_trend_hotels-1024x683.jpeg\" alt=\"\" data-id=\"3882\" data-link=\"https:\/\/wptesting.radiopark.de\/?attachment_id=3882\" class=\"wp-image-3882\" srcset=\"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/Radisson_blu_hotel_altstadt_deutscheStube_c_austria_trend_hotels-1024x683.jpeg 1024w, https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/Radisson_blu_hotel_altstadt_deutscheStube_c_austria_trend_hotels-300x200.jpeg 300w, https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/Radisson_blu_hotel_altstadt_deutscheStube_c_austria_trend_hotels-768x512.jpeg 768w, https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/Radisson_blu_hotel_altstadt_deutscheStube_c_austria_trend_hotels-1080x720.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG11530_ATH_Parkhotel_Schoenbrunn_Bar-scaled-1024x683.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG11530_ATH_Parkhotel_Schoenbrunn_Bar-scaled-1024x683.jpeg\" alt=\"\" data-id=\"3883\" data-link=\"https:\/\/wptesting.radiopark.de\/?attachment_id=3883\" class=\"wp-image-3883\" srcset=\"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG11530_ATH_Parkhotel_Schoenbrunn_Bar-scaled-1024x683.jpeg 1024w, https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG11530_ATH_Parkhotel_Schoenbrunn_Bar-scaled-300x200.jpeg 300w, https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG11530_ATH_Parkhotel_Schoenbrunn_Bar-scaled-768x512.jpeg 768w, https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG11530_ATH_Parkhotel_Schoenbrunn_Bar-scaled-1080x720.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption>PAW Bar Gloriette<\/figcaption><\/figure><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;gehen mit gest\u00e4rkter Zusammenarbeit aus dem Lockdown. Hamburg, 14. Mai 2021: Noch sind die Zimmer leer und die Bars geschlossen \u2013 seit Monaten k\u00f6nnen Hotels keine G\u00e4ste empfangen. Radiopark und Austria Trend Hotels nutzen diese ungew\u00f6hnlichen Zeiten f\u00fcr einen musikalischen Neustart. Seit \u00fcber 15 Jahren bespielen die Hamburger Musikspezialisten die H\u00e4user der renommierten \u00f6sterreichischen Hotelgruppe. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3884,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[14,15,46,18,105,56,57,12,30,32],"tags":[],"class_list":["post-3879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atmosphare","category-backgroundmusic-2","category-customers","category-hintergrundmusik-2","category-hotel-2","category-neue-kunden","category-new-customers","category-news","category-press-releases","category-pressemitteilungen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Musikalischer Neustart: Radiopark und Austria Trend Hotels... - Radiopark | Emotions in Music<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Musikalischer Neustart: Radiopark und Austria Trend Hotels... - Radiopark | Emotions in Music\" \/>\n<meta property=\"og:description\" content=\"&#8230;gehen mit gest\u00e4rkter Zusammenarbeit aus dem Lockdown. Hamburg, 14. Mai 2021: Noch sind die Zimmer leer und die Bars geschlossen \u2013 seit Monaten k\u00f6nnen Hotels keine G\u00e4ste empfangen. Radiopark und Austria Trend Hotels nutzen diese ungew\u00f6hnlichen Zeiten f\u00fcr einen musikalischen Neustart. Seit \u00fcber 15 Jahren bespielen die Hamburger Musikspezialisten die H\u00e4user der renommierten \u00f6sterreichischen Hotelgruppe. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/\" \/>\n<meta property=\"og:site_name\" content=\"Radiopark | Emotions in Music\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-14T07:32:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-14T07:32:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG218252_Austria_Trend_Hotel_Rathauspark_AuSZenansicht-1-1024x682.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernando Reyes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernando Reyes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/\"},\"author\":{\"name\":\"Fernando Reyes\",\"@id\":\"https:\/\/wptesting.radiopark.de\/en\/#\/schema\/person\/813758ef78212380bb798b0d68f5de7b\"},\"headline\":\"Musikalischer Neustart: Radiopark und Austria Trend Hotels&#8230;\",\"datePublished\":\"2021-05-14T07:32:54+00:00\",\"dateModified\":\"2021-05-14T07:32:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/\"},\"wordCount\":444,\"image\":{\"@id\":\"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG218252_Austria_Trend_Hotel_Rathauspark_AuSZenansicht-1.jpeg\",\"articleSection\":[\"Atmosph\u00e4re\",\"Backgroundmusic\",\"Customers\",\"Hintergrundmusik\",\"Hotel\",\"Neue Kunden\",\"New Customers\",\"News\",\"Press Releases\",\"Pressemitteilungen\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/\",\"url\":\"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/\",\"name\":\"Musikalischer Neustart: Radiopark und Austria Trend Hotels... - Radiopark | Emotions in Music\",\"isPartOf\":{\"@id\":\"https:\/\/wptesting.radiopark.de\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG218252_Austria_Trend_Hotel_Rathauspark_AuSZenansicht-1.jpeg\",\"datePublished\":\"2021-05-14T07:32:54+00:00\",\"dateModified\":\"2021-05-14T07:32:55+00:00\",\"author\":{\"@id\":\"https:\/\/wptesting.radiopark.de\/en\/#\/schema\/person\/813758ef78212380bb798b0d68f5de7b\"},\"breadcrumb\":{\"@id\":\"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/#primaryimage\",\"url\":\"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG218252_Austria_Trend_Hotel_Rathauspark_AuSZenansicht-1.jpeg\",\"contentUrl\":\"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG218252_Austria_Trend_Hotel_Rathauspark_AuSZenansicht-1.jpeg\",\"width\":3508,\"height\":2338,\"caption\":\"RHW Au\u00dfenansicht\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wptesting.radiopark.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Musikalischer Neustart: Radiopark und Austria Trend Hotels&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wptesting.radiopark.de\/en\/#website\",\"url\":\"https:\/\/wptesting.radiopark.de\/en\/\",\"name\":\"Radiopark | Emotions in Music\",\"description\":\"Music that matters\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wptesting.radiopark.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/wptesting.radiopark.de\/en\/#\/schema\/person\/813758ef78212380bb798b0d68f5de7b\",\"name\":\"Fernando Reyes\",\"url\":\"https:\/\/wptesting.radiopark.de\/en\/author\/fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Musikalischer Neustart: Radiopark und Austria Trend Hotels... - Radiopark | Emotions in Music","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Musikalischer Neustart: Radiopark und Austria Trend Hotels... - Radiopark | Emotions in Music","og_description":"&#8230;gehen mit gest\u00e4rkter Zusammenarbeit aus dem Lockdown. Hamburg, 14. Mai 2021: Noch sind die Zimmer leer und die Bars geschlossen \u2013 seit Monaten k\u00f6nnen Hotels keine G\u00e4ste empfangen. Radiopark und Austria Trend Hotels nutzen diese ungew\u00f6hnlichen Zeiten f\u00fcr einen musikalischen Neustart. Seit \u00fcber 15 Jahren bespielen die Hamburger Musikspezialisten die H\u00e4user der renommierten \u00f6sterreichischen Hotelgruppe. [&hellip;]","og_url":"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/","og_site_name":"Radiopark | Emotions in Music","article_published_time":"2021-05-14T07:32:54+00:00","article_modified_time":"2021-05-14T07:32:55+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG218252_Austria_Trend_Hotel_Rathauspark_AuSZenansicht-1-1024x682.jpeg","type":"image\/jpeg"}],"author":"Fernando Reyes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Fernando Reyes","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/#article","isPartOf":{"@id":"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/"},"author":{"name":"Fernando Reyes","@id":"https:\/\/wptesting.radiopark.de\/en\/#\/schema\/person\/813758ef78212380bb798b0d68f5de7b"},"headline":"Musikalischer Neustart: Radiopark und Austria Trend Hotels&#8230;","datePublished":"2021-05-14T07:32:54+00:00","dateModified":"2021-05-14T07:32:55+00:00","mainEntityOfPage":{"@id":"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/"},"wordCount":444,"image":{"@id":"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/#primaryimage"},"thumbnailUrl":"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG218252_Austria_Trend_Hotel_Rathauspark_AuSZenansicht-1.jpeg","articleSection":["Atmosph\u00e4re","Backgroundmusic","Customers","Hintergrundmusik","Hotel","Neue Kunden","New Customers","News","Press Releases","Pressemitteilungen"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/","url":"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/","name":"Musikalischer Neustart: Radiopark und Austria Trend Hotels... - Radiopark | Emotions in Music","isPartOf":{"@id":"https:\/\/wptesting.radiopark.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/#primaryimage"},"image":{"@id":"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/#primaryimage"},"thumbnailUrl":"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG218252_Austria_Trend_Hotel_Rathauspark_AuSZenansicht-1.jpeg","datePublished":"2021-05-14T07:32:54+00:00","dateModified":"2021-05-14T07:32:55+00:00","author":{"@id":"https:\/\/wptesting.radiopark.de\/en\/#\/schema\/person\/813758ef78212380bb798b0d68f5de7b"},"breadcrumb":{"@id":"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/#primaryimage","url":"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG218252_Austria_Trend_Hotel_Rathauspark_AuSZenansicht-1.jpeg","contentUrl":"https:\/\/wptesting.radiopark.de\/app\/uploads\/2021\/05\/VBG218252_Austria_Trend_Hotel_Rathauspark_AuSZenansicht-1.jpeg","width":3508,"height":2338,"caption":"RHW Au\u00dfenansicht"},{"@type":"BreadcrumbList","@id":"https:\/\/wptesting.radiopark.de\/en\/2021\/05\/14\/radiopark-austria-trend-hotels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wptesting.radiopark.de\/en\/"},{"@type":"ListItem","position":2,"name":"Musikalischer Neustart: Radiopark und Austria Trend Hotels&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/wptesting.radiopark.de\/en\/#website","url":"https:\/\/wptesting.radiopark.de\/en\/","name":"Radiopark | Emotions in Music","description":"Music that matters","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wptesting.radiopark.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/wptesting.radiopark.de\/en\/#\/schema\/person\/813758ef78212380bb798b0d68f5de7b","name":"Fernando Reyes","url":"https:\/\/wptesting.radiopark.de\/en\/author\/fr\/"}]}},"_links":{"self":[{"href":"https:\/\/wptesting.radiopark.de\/en\/wp-json\/wp\/v2\/posts\/3879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wptesting.radiopark.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wptesting.radiopark.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wptesting.radiopark.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wptesting.radiopark.de\/en\/wp-json\/wp\/v2\/comments?post=3879"}],"version-history":[{"count":3,"href":"https:\/\/wptesting.radiopark.de\/en\/wp-json\/wp\/v2\/posts\/3879\/revisions"}],"predecessor-version":[{"id":3885,"href":"https:\/\/wptesting.radiopark.de\/en\/wp-json\/wp\/v2\/posts\/3879\/revisions\/3885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wptesting.radiopark.de\/en\/wp-json\/wp\/v2\/media\/3884"}],"wp:attachment":[{"href":"https:\/\/wptesting.radiopark.de\/en\/wp-json\/wp\/v2\/media?parent=3879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wptesting.radiopark.de\/en\/wp-json\/wp\/v2\/categories?post=3879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wptesting.radiopark.de\/en\/wp-json\/wp\/v2\/tags?post=3879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}